{"id":854,"date":"2014-02-02T11:20:51","date_gmt":"2014-02-02T10:20:51","guid":{"rendered":"http:\/\/www.myparisagency.com\/blog\/?p=854"},"modified":"2014-02-07T13:03:28","modified_gmt":"2014-02-07T12:03:28","slug":"cavallotti","status":"publish","type":"post","link":"https:\/\/www.myparisagency.com\/blog\/fr\/2014\/02\/02\/cavallotti","title":{"rendered":"Cavallotti"},"content":{"rendered":"<p>Carr\u00e9 d&#8217;as pour ce magnifique <a title=\"Le Cavallotti, un tres bel appartement parisien \u00e0 louer meuble\" href=\"http:\/\/www.myparisagency.com\/fr\/appartements\/286\/cavallotti\">appartement de 2 pi\u00e8ces \u00e0 louer meubl\u00e9<\/a> et r\u00e9cemment refait \u00e0 neuf dans un style design. Au 2\u00e8me \u00e9tage sans ascenseur d&#8217;un immeuble agr\u00e9able de la rue Cavallotti, profitez d&#8217;un s\u00e9jour \u00e0 2 ou 4 personnes dans un bien de standing id\u00e9alement situ\u00e9 entre Blanche et Montmartre dans le quartier historique du 18\u00e8me arrondissement de Paris.<\/p>\n<p><a href=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/01\/110.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-855\" alt=\"1\" src=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/01\/110-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/01\/110-300x200.jpg 300w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/01\/110-450x300.jpg 450w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/01\/110.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>D&#8217;une surface de\u00a038 m<sup>2<\/sup>, le Cavallotti vous offre une bouff\u00e9e d&#8217;oxyg\u00e8ne au coeur de Paris avec un int\u00e9rieur stylis\u00e9 et \u00e9pur\u00e9. Le s\u00e9jour dispose d&#8217;un canap\u00e9 convertible confortable ouvert sur une TV \u00e0 \u00e9cran plat avec Internet en illimit\u00e9. L&#8217;espace d\u00eenatoire comprend une table confortable en face de la cuisine am\u00e9ricaine enti\u00e8rement \u00e9quip\u00e9e pour vous restaurer sur place. Savourez vos r\u00eaves dans la grande chambre double avec de nombreux espaces de rangements pour vos effets personnels. La douche de type pluie tropicale saura \u00e9galement vous s\u00e9duire. Les WC sont s\u00e9par\u00e9s pour garantir une parfaite intimit\u00e9 aux occupants.<\/p>\n<p><a href=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/02\/2.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-858\" alt=\"2\" src=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/02\/2-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/02\/2-300x200.jpg 300w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/02\/2-450x300.jpg 450w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2014\/02\/2.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Limite des communes des Batignolles-Monceau et de Montmartre, la rue Cavallotti a re\u00e7u en 1899 le nom du journaliste, publiciste et homme politique italien de gauche Felice Carlo Emmanuelle Cavallotti (Milan, le 6 d\u00e9cembre 1842 &#8211; Rome, le 6 mars 1898), mort dans un duel l&#8217;opposant \u00e0 Ferruccio Macola, le directeur de la Gazzetta di Venesia (de droite), qu&#8217;il avait insult\u00e9. Vous pourrez rejoindre \u00e0 pied les monuments centraux de la capitale :\u00a0Montmartre et sa basilique, le quartier de Pigalle, les puces de Clignancourt, le Canal de l&#8217;Ourq, la place de Clichy, Saint Lazare, la Villette et la Cit\u00e9 de la Science. Quelques stations de m\u00e9tro suffiront pour acc\u00e9der aux autres arrondissements parisiens (m\u00e9tro Place de Clichy ou Blanche, ligne 2 ou 13) : vous \u00eates directement sur les Champs Elys\u00e9es, \u00e0 Miromesnil, aux Invalides ou encore \u00e0 Montparnasse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carr\u00e9 d&#8217;as pour ce magnifique appartement de 2 pi\u00e8ces \u00e0 louer meubl\u00e9 et r\u00e9cemment refait \u00e0 neuf dans un style design. Au 2\u00e8me \u00e9tage sans ascenseur d&#8217;un immeuble agr\u00e9able de la rue Cavallotti, profitez d&#8217;un s\u00e9jour \u00e0 2 ou 4 personnes dans un bien de standing id\u00e9alement situ\u00e9 entre Blanche et Montmartre dans le quartier&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts\/854"}],"collection":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/comments?post=854"}],"version-history":[{"count":4,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts\/854\/revisions"}],"predecessor-version":[{"id":865,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts\/854\/revisions\/865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/media\/1037"}],"wp:attachment":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/media?parent=854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/categories?post=854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/tags?post=854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}