{"id":513,"date":"2013-09-05T15:27:11","date_gmt":"2013-09-05T14:27:11","guid":{"rendered":"http:\/\/www.myparisagency.com\/blog\/?p=513"},"modified":"2013-09-30T12:44:50","modified_gmt":"2013-09-30T11:44:50","slug":"jonquoy","status":"publish","type":"post","link":"https:\/\/www.myparisagency.com\/blog\/fr\/2013\/09\/05\/jonquoy","title":{"rendered":"Jonquoy"},"content":{"rendered":"<p>Paris vous ouvre ses portes pour un s\u00e9jour en famille dans ce superbe appartement de 3 pi\u00e8ces \u00e0 l&#8217;espace parfaitement optimis\u00e9 pour 4 personnes.\u00a0Au 2\u00e8me \u00e9tage sans ascenseur d&#8217;un immeuble agr\u00e9able de la rue Jonquoy, profitez d&#8217;un emplacement id\u00e9al pour d\u00e9couvrir les plus beaux monuments de la capitale.<\/p>\n<p><a href=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/09\/1.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-517\" src=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/09\/1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p>D&#8217;une surface de 55 m<sup>2<\/sup>, le Jonquoy est un v\u00e9ritable havre de paix qui vous procurera douceur et bien-\u00eatre pour votre vir\u00e9e parisienne. La pi\u00e8ce \u00e0 vivre confortable est ouverte sur une cuisine am\u00e9ricaine enti\u00e8rement \u00e9quip\u00e9e pour vous restaurer sur place. Deux chambres doubles, l&#8217;une avec un grand lit, l&#8217;autre disposant d&#8217;un lit mont\u00e9 sur v\u00e9rins hydrauliques pour une espace de vie durant la journ\u00e9e modulable en coin nuit pour le soir. Une belle salle de bains avec baignoire et douche compl\u00e8te ce bien authentique.<\/p>\n<p><a href=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/09\/2.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-518\" src=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/09\/2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/09\/2-300x200.jpg 300w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/09\/2-448x300.jpg 448w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/09\/2.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Le quartier de Plaisance se trouve\u00a0entre le boulevard Brune et les abords de la gare de Paris-Montparnasse et entre la rue Vercing\u00e9torix et l&#8217;avenue du Maine. Ainsi, vous pourrez rejoindre les monuments les plus embl\u00e9matiques de la capitale : la place Denfert Rochereau, la gare Montparnasse, la rue de Rennes, Gait\u00e9 et ses th\u00e9\u00e2tres&#8230; Accessible gr\u00e2ce au m\u00e9tro Plaisance au pied de l&#8217;appartement (m\u00e9tro 13) rejoignez en toute facilit\u00e9 les autres quartiers de vos envies.<\/p>\n<p style=\"text-align: center\"><span style=\"color: #ff6600\"><strong>Rendez-vous vite pour r\u00e9server<\/strong> <\/span>:\u00a0http:\/\/www.myparisagency.com\/fr\/appartements\/229\/jonquoy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paris vous ouvre ses portes pour un s\u00e9jour en famille dans ce superbe appartement de 3 pi\u00e8ces \u00e0 l&#8217;espace parfaitement optimis\u00e9 pour 4 personnes.\u00a0Au 2\u00e8me \u00e9tage sans ascenseur d&#8217;un immeuble agr\u00e9able de la rue Jonquoy, profitez d&#8217;un emplacement id\u00e9al pour d\u00e9couvrir les plus beaux monuments de la capitale. D&#8217;une surface de 55 m2, le Jonquoy&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts\/513"}],"collection":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/comments?post=513"}],"version-history":[{"count":6,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts\/513\/revisions"}],"predecessor-version":[{"id":1206,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts\/513\/revisions\/1206"}],"wp:attachment":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/media?parent=513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/categories?post=513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/tags?post=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}