{"id":485,"date":"2013-08-23T16:35:18","date_gmt":"2013-08-23T15:35:18","guid":{"rendered":"http:\/\/www.myparisagency.com\/blog\/?p=485"},"modified":"2013-09-30T12:46:21","modified_gmt":"2013-09-30T11:46:21","slug":"bastille","status":"publish","type":"post","link":"https:\/\/www.myparisagency.com\/blog\/fr\/2013\/08\/23\/bastille","title":{"rendered":"Bastille"},"content":{"rendered":"<p>R\u00e9cemment r\u00e9nov\u00e9 avec go\u00fbt, cet appartement de 2 pi\u00e8ces vous plonge au c\u0153ur d\u2019un quartier branch\u00e9 dans la rue de Lappe, r\u00e9put\u00e9e pour ses bars internationaux. Grimpez un \u00e9tage sans ascenseur pour acc\u00e9der \u00e0 l&#8217;appartement, id\u00e9al situ\u00e9 dans le 11\u00e8me arrondissement de Paris.<\/p>\n<p><a href=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/12.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-488\" src=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/12-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/12-300x200.jpg 300w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/12-450x300.jpg 450w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/12.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>D&#8217;une surface de 23 m2, le Bastille d\u00e9voile un espace parfaitement optimis\u00e9 pour le s\u00e9jour de 4 personnes. Le salon aux tons rouges et noirs est ouvert sur la cuisine am\u00e9ricaine enti\u00e8rement \u00e9quip\u00e9e pour vous restaurer sur place. En plus du canap\u00e9 convertible, la chambre double offre deux couchages confortable avec un acc\u00e8s direct \u00e0 la salle de bains dot\u00e9e d&#8217;une baignoire et d&#8217;un lavabo et des WC.<\/p>\n<p><a href=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/22.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-489\" src=\"http:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/22-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/22-300x200.jpg 300w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/22-450x300.jpg 450w, https:\/\/www.myparisagency.com\/blog\/wp-content\/uploads\/2013\/08\/22.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Proche de tout mais cependant totalement au calme, profitez d&#8217;un emplacement exceptionnel \u00e0 deux pas de la mythique Place de la Bastille. Rendez-vous\u00a0\u00e0 pied vers de nombreux lieux touristiques incontournables :\u00a0la Place de la R\u00e9publique, M\u00e9nilmontant, le Cimeti\u00e8re du P\u00e8re Lachaise, Belleville, le Marais, le Canal Saint Martin ou m\u00eame le Parc des Buttes Chaumont. Pour vos autres d\u00e9placements, empruntez facilement les transports en commun pour rejoindre les autres quartiers parisiens (Bastille, ligne 1, 5 et la 8).<\/p>\n<p style=\"text-align: center\"><span style=\"color: #ff6600\"><strong>Rendez-vous vite pour r\u00e9server<\/strong> <\/span>:\u00a0http:\/\/www.myparisagency.com\/fr\/appartements\/225\/bastille<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9cemment r\u00e9nov\u00e9 avec go\u00fbt, cet appartement de 2 pi\u00e8ces vous plonge au c\u0153ur d\u2019un quartier branch\u00e9 dans la rue de Lappe, r\u00e9put\u00e9e pour ses bars internationaux. Grimpez un \u00e9tage sans ascenseur pour acc\u00e9der \u00e0 l&#8217;appartement, id\u00e9al situ\u00e9 dans le 11\u00e8me arrondissement de Paris. D&#8217;une surface de 23 m2, le Bastille d\u00e9voile un espace parfaitement optimis\u00e9&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts\/485"}],"collection":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/comments?post=485"}],"version-history":[{"count":5,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts\/485\/revisions"}],"predecessor-version":[{"id":1209,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/posts\/485\/revisions\/1209"}],"wp:attachment":[{"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/media?parent=485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/categories?post=485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myparisagency.com\/blog\/wp-json\/wp\/v2\/tags?post=485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}